{"id":43758,"date":"2026-08-31T00:00:00","date_gmt":"2026-08-30T23:00:00","guid":{"rendered":"https:\/\/www1.eurogate.de\/karriere\/job\/fachhandwerker-m-w-d-elektrotechnik\/"},"modified":"2026-08-31T00:00:00","modified_gmt":"2026-08-30T23:00:00","slug":"fachhandwerker-m-w-d-elektrotechnik","status":"publish","type":"job","link":"https:\/\/www1.eurogate.de\/karriere\/job\/fachhandwerker-m-w-d-elektrotechnik\/","title":{"rendered":"Fachhandwerker (m\/w\/d) Elektrotechnik"},"content":{"rendered":"","protected":false},"template":"","arbeitsfeld":[123,134,129,131,138,141,139,146,133,127,125,124,132,128,135,130,140,137,136],"gesellschaft":[122],"standort":[108],"stellenart":[100],"class_list":["post-43758","job","type-job","status-publish","hentry","arbeitsfeld-administration","arbeitsfeld-einkauf-materialwirtschaft","arbeitsfeld-engineering","arbeitsfeld-finanz-rechnungswesen-controlling","arbeitsfeld-gewerblich-hafenlogistik","arbeitsfeld-gewerblich-handwerk","arbeitsfeld-gewerblich-lagerlogistik","arbeitsfeld-hafenarbeit","arbeitsfeld-human-resources-recht","arbeitsfeld-it","arbeitsfeld-kaufmaennische","arbeitsfeld-kaufmaennischer-bereich","arbeitsfeld-marketing-vertrieb-pr","arbeitsfeld-sonstige","arbeitsfeld-sonstiges","arbeitsfeld-technik-ingenieurwissenschaftlicher-bereich","arbeitsfeld-technik-handwerk","arbeitsfeld-transport-logistik","arbeitsfeld-umwelt-energiemanagement","gesellschaft-eurogate-technical-services-gmbh-wilhelmshaven","standort-wilhelmshaven","stellenart-vollzeit"],"stellenid":"1179","satzstellentitel":"Du suchst eine neue Herausforderung, bist lernwillig und bestrebt dein fachspezifisches Know-how stetig zu erweitern oder zu ver\u00e4ndern und es motiviert dich im Bereich Energieversorgung & Infrastruktur-Management einzutauchen, dann hast du jetzt am Standort Wilhelmshaven die M\u00f6glichkeit dazu!","stellentitel":"Fachhandwerker (m\/w\/d) Elektrotechnik","aufgabentitel":"Das zeichnet deine T\u00e4tigkeit aus:","aufgaben":"In deiner Position als Fachhandwerker (m\/w\/d) bist du f\u00fcr die Instandhaltung und Pr\u00fcfung der elektrischen Anlagen und Betriebsmittel der technischen Infrastruktur im Hafengebiet von Wilhelmshaven zust\u00e4ndig. Dar\u00fcber hinaus \u00fcbernimmst du folgende T\u00e4tigkeiten: <ul><li>Gewerke \u00fcbergreifende Instandhaltung, Steuerung und Optimierung von technischen Anlagen der Geb\u00e4udeausstattung und Fl\u00e4cheninfrastruktur<\/li><li>Selbstst\u00e4ndige Nachr\u00fcstungen und Erweiterungen von geb\u00e4udetechnischen Anlagen mittleren und kleineren Umfangs<\/li><li>Pr\u00fcfung der Systeme unserer technischen Anlagen, wie z.B. Brandmeldeanlagen, Geb\u00e4udeleittechnik, Unterspannungsversorgung, Rauch und W\u00e4rmeabzugsanlagen sowie auch Rauchschutzdruckanlagen<\/li><li>Koordination von Fremdfirmen im Rahmen von Terminabsprachen, Einweisungen vor Ort sowie Arbeitsabnahmen und Dokumentation<\/li><\/ul>","profiltitel":"Das solltest du mitbringen:","profil":"<ul><li><b>Fachkompetenz:<\/b> Erfolgreich abgeschlossene Berufsausbildung als Elektrotechniker\/in mit Fachrichtung Energie- und Geb\u00e4udetechnik oder eine vergleichbare Ausbildung<\/li><li><b>Erfahrung:<\/b> Mehrj\u00e4hrige, idealerweise Gewerke \u00fcbergreifende Berufserfahrung im Bereich Installation und Instandsetzung von Anlagen und Betriebsmitteln<\/li><li>Erste SPS-Kenntnisse w\u00e4ren w\u00fcnschenswert<\/li><li>H\u00f6hentauglichkeit und k\u00f6rperliche Belastbarkeit<\/li><li><b>Mobilit\u00e4t: <\/b>F\u00fchrerschein Klasse B, idealerweise einen Staplerschein<\/li><\/ul>","bietentitel":"Wir bieten","bieten":"\u2026 ein Arbeitsumfeld, das auf dem Fundament traditioneller Wurzeln und Werte basiert, sich kontinuierlich den Herausforderungen der Zukunft stellt und weiterentwickelt. Das beinhaltet nat\u00fcrlich: \u2022 Attraktive tarifliche Entgelt- und Rahmenbedingungen \u2022 Ein zeitgem\u00e4\u00dfes Modell der betrieblich unterst\u00fctzten Altersvorsorge \u2022 Eine Vielzahl standortabh\u00e4ngiger Bezuschussungen, wie z.B. zur Kinderbetreuung, zur \u00a0 Nutzung von \u00d6PNV-Angeboten oder zur Kantinenverpflegung  \u2022 Angebote des betrieblichen Gesundheitsmanagements wie z.B. \u00a0 Firmenfitness oder eine betrieblich gef\u00f6rderte Sozialberatung \u2022 Spannende Entwicklungsm\u00f6glichkeiten in einem vielseitigen und gut\u00a0 \u00a0 aufgestellten Konzern ","unternehmensbereich":"Technik, Handwerk","standorte":"Wilhelmshaven","descriptionurl":"https:\/\/recruitingapp-346.de.umantis.com\/Vacancies\/1179\/Description\/1?lang=ger","applicationurl":"https:\/\/recruitingapp-346.de.umantis.com\/Vacancies\/1179\/Application\/CheckLogin\/1?lang=ger","befristung":"","online_seit":"31.08.2026","headerbild":"https:\/\/recruitingapp-346.de.umantis.com\/Vacancies\/1179\/Description\/1?ShowDocument=2","gesellschaftsbeschreibung":"EUROGATE Technical Services ist das technische Dienstleistungsunternehmen der EUROGATE-Gruppe mit den Standorten in Bremerhaven, Hamburg und Wilhelmshaven. Das Unternehmen garantiert die st\u00e4ndige und zuverl\u00e4ssige Verf\u00fcgbarkeit der gesamten Hafentechnik. Unsere Mitarbeiter befassen sich mit allen Aspekten im Lebenslauf der komplexen Anlagen und Systeme: von der Konzeption, Planung, Inbetriebnahme und Instandhaltung bis hin zur technischen Weiterentwicklung.   Das Leistungsspektrum von EUROGATE Technical Services umfasst die Themengebiete Krananlagen, Lastaufnahmemittel, Fahrzeugtechnik, Automatisierung, Prozessleittechnik, Funk- und Kommunikationstechnik, Klimatechnik, F\u00f6rder- und Lagertechnik bis hin zum Bauwesen, Facility Management sowie der Energieversorgung.   EUROGATE Technical Services erstellt zudem f\u00fcr seine Kunden technische Spezifikationen und Gutachten, begleitet Ausschreibungen bei Investitionsvorhaben und stellt eine z\u00fcgige und sichere Inbetriebnahme und Abnahme der technischen Anlagen und Bauten sicher.   In Bremerhaven betreut die EUROGATE Technical Services dar\u00fcber hinaus das Stromversorgungsnetz des Stadtbremischen \u00dcberseehafens. ","gesellschaftsname":"EUROGATE Technical Services GmbH, Wilhelmshaven","_links":{"self":[{"href":"https:\/\/www1.eurogate.de\/karriere\/wp-json\/wp\/v2\/job\/43758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www1.eurogate.de\/karriere\/wp-json\/wp\/v2\/job"}],"about":[{"href":"https:\/\/www1.eurogate.de\/karriere\/wp-json\/wp\/v2\/types\/job"}],"wp:attachment":[{"href":"https:\/\/www1.eurogate.de\/karriere\/wp-json\/wp\/v2\/media?parent=43758"}],"wp:term":[{"taxonomy":"arbeitsfeld","embeddable":true,"href":"https:\/\/www1.eurogate.de\/karriere\/wp-json\/wp\/v2\/arbeitsfeld?post=43758"},{"taxonomy":"gesellschaft","embeddable":true,"href":"https:\/\/www1.eurogate.de\/karriere\/wp-json\/wp\/v2\/gesellschaft?post=43758"},{"taxonomy":"standort","embeddable":true,"href":"https:\/\/www1.eurogate.de\/karriere\/wp-json\/wp\/v2\/standort?post=43758"},{"taxonomy":"stellenart","embeddable":true,"href":"https:\/\/www1.eurogate.de\/karriere\/wp-json\/wp\/v2\/stellenart?post=43758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}